{"id":3374,"date":"2025-02-22T20:39:10","date_gmt":"2025-02-22T20:39:10","guid":{"rendered":"https:\/\/fitzenforlife.com\/?page_id=3374"},"modified":"2025-02-22T20:40:24","modified_gmt":"2025-02-22T20:40:24","slug":"privacy-policy-2","status":"publish","type":"page","link":"https:\/\/fitzenforlife.com\/fr\/privacy-policy-2\/","title":{"rendered":"Politique de Confidentialit\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3374\" class=\"elementor elementor-3374\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3568d867 e-flex e-con-boxed e-con e-parent\" data-id=\"3568d867\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65b70063 elementor-widget elementor-widget-text-editor\" data-id=\"65b70063\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\nBienvenue sur https:\/\/fitzenforlife.com (le \u00ab Site \u00bb). Nous comprenons que la confidentialit\u00e9 en ligne est importante pour les utilisateurs de notre site, en particulier lorsqu'ils exercent des affaires. Cette d\u00e9claration r\u00e9git nos politiques de confidentialit\u00e9 \u00e0 l'\u00e9gard des utilisateurs du site (\"visiteurs\") qui visitent sans effectuer de transactions commerciales et les visiteurs qui s'inscrivent pour effectuer des transactions commerciales sur le site et utilisent les diff\u00e9rents services offerts par\n\nFitZenforLife (collectivement, \u00ab Services \u00bb) (\u00ab Clients autoris\u00e9s \u00bb).\n<\/p>\n\n<h3>\u00ab Informations Personnellement Identifiables \u00bb<\/h3>\n<p>D\u00e9signe toute information qui identifie ou peut \u00eatre utilis\u00e9e pour identifier, contacter ou localiser la personne \u00e0 laquelle ces informations se r\u00e9f\u00e8rent, y compris, mais sans s'y limiter, le nom, l'adresse, le num\u00e9ro de t\u00e9l\u00e9phone, le num\u00e9ro de t\u00e9l\u00e9copieur, l'adresse \u00e9lectronique, les profils financiers, le num\u00e9ro de s\u00e9curit\u00e9 sociale et les informations de carte de cr\u00e9dit. Les informations personnellement identifiables n'incluent pas les informations collect\u00e9es anonymement (c'est-\u00e0-dire sans identification de l'utilisateur individuel) ou les informations d\u00e9mographiques non li\u00e9es \u00e0 une personne identifi\u00e9e.<\/p>\n\n<h3>Quelles Informations Personnellement Identifiables sont Collect\u00e9es ?<\/h3>\n<p>\nNous pouvons recueillir des informations de base sur le profil de l'utilisateur aupr\u00e8s de tous nos visiteurs. Nous recueillons les informations suppl\u00e9mentaires suivantes aupr\u00e8s de nos clients autoris\u00e9s : le nom, l'adresse e-mail, le num\u00e9ro de t\u00e9l\u00e9phone, l'adresse, les informations de profil des m\u00e9dias sociaux, <\/p>\n\n<h3>Quelles organisations collectent les informations ?<\/h3>\n<p>En plus de notre collecte directe d'informations, nos fournisseurs de services tiers (tels que les soci\u00e9t\u00e9s de cartes de cr\u00e9dit, les centres de compensation et les banques) qui peuvent fournir des services tels que des services de cr\u00e9dit, d'assurance et d'entiercement peuvent collecter ces informations aupr\u00e8s de nos visiteurs et clients autoris\u00e9s. Nous ne contr\u00f4lons pas la fa\u00e7on dont ces tiers utilisent ces informations, mais nous leur demandons de divulguer comment ils utilisent les informations personnelles qui leur sont fournies par les visiteurs et les clients autoris\u00e9s. Certains de ces tiers peuvent \u00eatre des interm\u00e9diaires qui agissent uniquement en tant que liens dans la cha\u00eene de distribution, et ne stockent, ne conservent pas ou n'utilisent pas les informations qui leur sont donn\u00e9es.<\/p>\n\n<h3>Comment le Site utilise-t-il les Informations Personnellement Identifiables ?<\/h3>\n<p>Nous utilisons des informations personnellement identifiables pour personnaliser le site, pour faire des offres de services appropri\u00e9es et pour r\u00e9pondre aux demandes d'achat et de vente sur le site. Nous pouvons envoyer des courriels aux visiteurs et aux clients autoris\u00e9s au sujet de recherches ou d'opportunit\u00e9s d'achat et de vente sur le site ou d'informations relatives \u00e0 l'objet du site. Nous pouvons \u00e9galement utiliser des informations personnellement identifiables pour contacter les visiteurs et les clients autoris\u00e9s en r\u00e9ponse \u00e0 des demandes sp\u00e9cifiques, ou pour fournir les informations demand\u00e9es.<\/p>\n\n<h3>Avec qui l'information peut-elle \u00eatre partag\u00e9e ?<\/h3>\n<p>Les informations personnellement identifiables sur les clients autoris\u00e9s peuvent \u00eatre partag\u00e9es avec d'autres clients autoris\u00e9s qui souhaitent \u00e9valuer les transactions potentielles avec d'autres clients autoris\u00e9s. Nous pouvons partager des informations agr\u00e9g\u00e9es sur nos visiteurs, y compris les donn\u00e9es d\u00e9mographiques de nos visiteurs et clients autoris\u00e9s, avec nos agences affili\u00e9es et nos fournisseurs tiers. Nous offrons \u00e9galement la possibilit\u00e9 de \u00ab refuser \u00bb de recevoir des informations ou d'\u00eatre contact\u00e9 par nous ou par toute agence agissant en notre nom.<\/p>\n\n<h3>Comment les informations personnellement identifiables sont-elles stock\u00e9es ?<\/h3>\n<p>Les informations personnellement identifiables collect\u00e9es par FitZenforLife sont stock\u00e9es en toute s\u00e9curit\u00e9 et ne sont pas accessibles aux tiers ou aux employ\u00e9s de FitZenforLife, sauf pour une utilisation comme indiqu\u00e9 ci-dessus.<\/p>\n\n<h3>Quels sont les choix disponibles pour les visiteurs en ce qui concerne la collecte, l'utilisation et la distribution des informations ?<\/h3>\n<p>\nLes visiteurs et les clients autoris\u00e9s peuvent refuser de recevoir ou d'\u00eatre contact\u00e9s par nous et\/ou nos fournisseurs et agences affili\u00e9es en r\u00e9pondant aux courriels conform\u00e9ment aux instructions, ou en nous contactant \u00e0 l'adresse contact@fitzenforlife.com <\/p>\n\t<h3>Cookie Google AdSense et DoubleClick<\/h3>\n\t<p>Google, en tant que fournisseur tiers, utilise des cookies pour diffuser des publicit\u00e9s sur notre service.<\/p>\n<h3>Cookies<\/h3>\n<p>Un cookie est une cha\u00eene d'informations qu'un site Web stocke sur l'ordinateur d'un visiteur et que le navigateur du visiteur fournit au site Web chaque fois que le visiteur revient.<\/p>\n<p>Nous utilisons des \"cookies\" pour collecter des informations. Vous pouvez demander \u00e0 votre navigateur de refuser tous les cookies ou d'indiquer quand un cookie est envoy\u00e9. Cependant, si vous n'acceptez pas les cookies, vous ne pourrez peut-\u00eatre pas utiliser certaines parties de notre service.<\/p>\n\n<h3>Les cookies sont-ils utilis\u00e9s sur le site ?<\/h3>\n<p>\nLes cookies sont utilis\u00e9s pour diverses raisons. Nous utilisons des cookies pour obtenir des informations sur les pr\u00e9f\u00e9rences de nos visiteurs et les services qu'ils choisissent. Nous utilisons \u00e9galement des cookies \u00e0 des fins de s\u00e9curit\u00e9 pour prot\u00e9ger nos clients autoris\u00e9s. Par exemple, si un client autoris\u00e9 est connect\u00e9 et que le site n'est pas utilis\u00e9 pendant plus de 10 minutes, nous d\u00e9connecterons automatiquement le client autoris\u00e9. Les visiteurs qui ne souhaitent pas que des cookies soient plac\u00e9s sur leurs ordinateurs doivent configurer leurs navigateurs pour refuser les cookies avant d'utiliser https:\/\/fittenforlife.com, avec l'inconv\u00e9nient que certaines fonctionnalit\u00e9s du site Web peuvent ne pas fonctionner correctement sans l'aide de cookies.\n<\/p>\n\n<h3>Cookies utilis\u00e9s par nos fournisseurs de services<\/h3>\n<p>Nos fournisseurs de services utilisent des cookies et ces cookies peuvent \u00eatre stock\u00e9s sur votre ordinateur lorsque vous visitez notre site Web. Vous pouvez trouver plus de d\u00e9tails sur les cookies utilis\u00e9s sur notre page d'informations sur les cookies.<\/p>\n\n<h3>Comment FitZenforLife utilise-t-il les informations de connexion ?<\/h3>\n<p>\n FitZenforLife utilise les informations de connexion, y compris, mais sans s'y limiter, les adresses IP, les FAI et les types de navigateur, la version du navigateur, les pages visit\u00e9es, la date et l'heure de la visite, pour analyser les tendances, administrer le site, suivre le mouvement et l'utilisation d'un utilisateur et recueillir des informations d\u00e9mographiques g\u00e9n\u00e9rales.\n<\/p>\n\n<h3>Quels partenaires ou fournisseurs de services ont acc\u00e8s aux informations personnellement identifiables des visiteurs et\/ou des clients autoris\u00e9s sur le site ?<\/h3>\n<p>\n FitZenforLife a conclu et continuera \u00e0 conclure des partenariats et d'autres affiliations avec un certain nombre de fournisseurs. Ces fournisseurs peuvent avoir acc\u00e8s \u00e0 certaines informations personnellement identifiables sur la n\u00e9cessit\u00e9 de conna\u00eetre la base de l'\u00e9valuation des clients autoris\u00e9s pour l'admissibilit\u00e9 au service. Notre politique de confidentialit\u00e9 ne couvre pas leur collecte ou leur utilisation de ces informations. \n<\/p>\n\n<h3>Comment le site prot\u00e8ge-t-il les informations personnellement identifiables ?<\/h3>\n<p>Tous nos employ\u00e9s connaissent nos politiques et nos pratiques de s\u00e9curit\u00e9. Les informations personnellement identifiables de nos visiteurs et clients autoris\u00e9s ne sont accessibles qu'\u00e0 un nombre limit\u00e9 d'employ\u00e9s qualifi\u00e9s qui re\u00e7oivent un mot de passe afin d'acc\u00e9der aux informations. Nous auditons r\u00e9guli\u00e8rement nos syst\u00e8mes et processus de s\u00e9curit\u00e9. Les informations sensibles, telles que les num\u00e9ros de carte de cr\u00e9dit ou les num\u00e9ros de s\u00e9curit\u00e9 sociale, sont prot\u00e9g\u00e9es par des protocoles de cryptage, en place pour prot\u00e9ger les informations envoy\u00e9es sur Internet. Bien que nous prenions des mesures commercialement raisonnables pour maintenir un site s\u00e9curis\u00e9, les communications \u00e9lectroniques et les bases de donn\u00e9es sont sujettes \u00e0 des erreurs, \u00e0 des falsifications et \u00e0 des effractions, et nous ne pouvons pas garantir ou garantir que de tels \u00e9v\u00e9nements n'auront pas lieu et nous ne serons pas responsables envers les visiteurs ou les clients autoris\u00e9s de tels \u00e9v\u00e9nements.<\/p>\n\n<h3>Comment les visiteurs peuvent-ils corriger toute inexactitude dans les informations personnellement identifiables ?<\/h3>\n<p>\nLes visiteurs et les clients autoris\u00e9s peuvent nous contacter pour mettre \u00e0 jour les informations personnellement identifiables \u00e0 leur sujet ou pour corriger toute inexactitude en nous envoyant un courriel \u00e0 contact@fitzenforlife.com.\n<\/p>\n\n<h3>Un visiteur peut-il supprimer ou d\u00e9sactiver les informations personnellement identifiables collect\u00e9es par le site ?<\/h3>\n<p>Nous fournissons aux visiteurs et aux clients autoris\u00e9s un m\u00e9canisme pour supprimer\/d\u00e9sactiver les informations personnellement identifiables de la base de donn\u00e9es du site en contactant. Cependant, en raison des sauvegardes et des enregistrements de suppressions, il peut \u00eatre impossible de supprimer l'entr\u00e9e d'un visiteur sans conserver certaines informations r\u00e9siduelles. Une personne qui demande que les informations personnellement identifiables soient d\u00e9sactiv\u00e9es verront ces informations fonctionnellement supprim\u00e9es, et nous ne vendrons, ne transf\u00e9rerons ni n'utiliserons pas d'informations personnellement identifiables relatives \u00e0 cette personne de quelque mani\u00e8re que ce soit \u00e0 l'avenir.<\/p>\n\n<h3>Vos droits<\/h3>\n<p>\nCe sont des droits r\u00e9sum\u00e9s que vous avez en vertu de la loi sur la protection des donn\u00e9es :\n<ul>\n<li>The right to access<\/li>\n<li>The right to rectification<\/li>\n<li>The right to erasure<\/li>\n<li>The right to restrict processing<\/li>\n<li>The right to object to processing<\/li>\n<li>The right to data portability<\/li>\n<li>The right to complain to a supervisory authority<\/li>\n<li>The right to withdraw consent<\/li>\n<\/ul>\n<\/p>\n\n<h3>Vie Priv\u00e9e des Enfants<\/h3>\n<p>Notre service ne s'adresse pas aux \"enfants\", aux personnes de moins de 18 ans, et nous ne recueillons pas sciemment d'informations personnellement identifiables aupr\u00e8s d'enfants de moins de 18 ans.<\/p>\n<p>Si vous \u00eates un parent ou un tuteur et que vous savez que votre enfant nous a fourni des informations personnelles, veuillez nous contacter imm\u00e9diatement aux coordonn\u00e9es fournies. Si nous apprenons que des enfants de moins de 18 ans ont fourni des informations personnelles, nous supprimerons imm\u00e9diatement les informations de nos serveurs.<\/p>\n\n\t<h3>Respect Des Lois<\/h3>\n\t<p>Divulgation d'informations personnellement identifiables pour se conformer \u00e0 la loi. Nous divulguerons des renseignements personnellement identifiables afin de nous conformer \u00e0 une ordonnance du tribunal ou \u00e0 une assignation \u00e0 compara\u00eetre ou \u00e0 une demande d'un organisme d'application de la loi de divulguer des informations. Nous divulguerons \u00e9galement des informations personnellement identifiables lorsque cela est raisonnablement n\u00e9cessaire pour prot\u00e9ger la s\u00e9curit\u00e9 de nos visiteurs et clients autoris\u00e9s.<\/p>\n\n\n<h3>Que se passe-t-il si la politique de confidentialit\u00e9 change ?<\/h3>\n<p>Nous insuerons nos visiteurs et clients autoris\u00e9s des modifications apport\u00e9es \u00e0 notre politique de confidentialit\u00e9 en publiant ces modifications sur le site. Cependant, si nous modifions notre politique de confidentialit\u00e9 d'une mani\u00e8re qui pourrait entra\u00eener la divulgation d'informations personnellement identifiables qu'un visiteur ou un client autoris\u00e9 a pr\u00e9c\u00e9demment demand\u00e9 \u00e0 ne pas divulguer, nous contacterons ce visiteur ou ce client autoris\u00e9 pour permettre \u00e0 ce visiteur ou client autoris\u00e9 d'emp\u00eacher une telle divulgation.<\/p>\n\n<h3>Links<\/h3>\n<p>\n Https:\/\/fitzenforlife.com contient des liens vers d'autres sites Web. Veuillez noter que lorsque vous cliquez sur l'un de ces liens, vous vous d\u00e9placez vers un autre site Web. Nous vous encourageons \u00e0 lire les d\u00e9clarations de confidentialit\u00e9 de ces sites li\u00e9s car leurs politiques de confidentialit\u00e9 peuvent diff\u00e9rer des n\u00f4tres.\n<\/p>\n\n<h3>Contactez-Nous<\/h3>\n<p>Si vous avez des questions concernant cette politique de confidentialit\u00e9, veuillez nous contacter \u00e0 contact@fitzenforlife.com <\/p>\n<hr \/>\n<p>Derni\u00e8re mise \u00e0 jour : 22 f\u00e9vrier 2025<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Welcome to https:\/\/fitzenforlife.com (the \u201cSite\u201d). We understand that privacy online is important to users of our Site, especially when conducting business. This statement governs our privacy policies with respect to those users of the Site (\u201cVisitors\u201d) who visit without transacting business and Visitors who register to transact business on the Site and make use of [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3374","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fitzenforlife.com\/fr\/wp-json\/wp\/v2\/pages\/3374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitzenforlife.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fitzenforlife.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fitzenforlife.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fitzenforlife.com\/fr\/wp-json\/wp\/v2\/comments?post=3374"}],"version-history":[{"count":4,"href":"https:\/\/fitzenforlife.com\/fr\/wp-json\/wp\/v2\/pages\/3374\/revisions"}],"predecessor-version":[{"id":3378,"href":"https:\/\/fitzenforlife.com\/fr\/wp-json\/wp\/v2\/pages\/3374\/revisions\/3378"}],"wp:attachment":[{"href":"https:\/\/fitzenforlife.com\/fr\/wp-json\/wp\/v2\/media?parent=3374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}